{"id":74938,"date":"2025-01-23T15:42:34","date_gmt":"2025-01-23T20:42:34","guid":{"rendered":"https:\/\/www.nosm.ca\/wp-content\/uploads\/2025\/01\/Dr.-DellaVedova_2-e1576782988418-aspect-ratio-315x216-2.jpg"},"modified":"2025-01-23T15:42:34","modified_gmt":"2025-01-23T20:42:34","slug":"dr-dellavedova_2-e1576782988418-aspect-ratio-315x216-2-2","status":"inherit","type":"attachment","link":"https:\/\/www.nosm.ca\/fr\/dr-dellavedova_2-e1576782988418-aspect-ratio-315x216-2-2\/","title":{"rendered":"Dr.-DellaVedova_2-e1576782988418-aspect-ratio-315&#215;216-2"},"author":16,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-74938","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.nosm.ca\/wp-content\/uploads\/2019\/12\/Dr.-DellaVedova_2-e1576782988418-aspect-ratio-315x216-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"206\" src=\"https:\/\/www.nosm.ca\/wp-content\/uploads\/2019\/12\/Dr.-DellaVedova_2-e1576782988418-aspect-ratio-315x216-2-300x206.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.nosm.ca\/wp-content\/uploads\/2019\/12\/Dr.-DellaVedova_2-e1576782988418-aspect-ratio-315x216-2-300x206.jpg 300w, https:\/\/www.nosm.ca\/wp-content\/uploads\/2019\/12\/Dr.-DellaVedova_2-e1576782988418-aspect-ratio-315x216-2-1024x702.jpg 1024w, https:\/\/www.nosm.ca\/wp-content\/uploads\/2019\/12\/Dr.-DellaVedova_2-e1576782988418-aspect-ratio-315x216-2-150x103.jpg 150w, https:\/\/www.nosm.ca\/wp-content\/uploads\/2019\/12\/Dr.-DellaVedova_2-e1576782988418-aspect-ratio-315x216-2-768x526.jpg 768w, https:\/\/www.nosm.ca\/wp-content\/uploads\/2019\/12\/Dr.-DellaVedova_2-e1576782988418-aspect-ratio-315x216-2.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1500,"height":1028,"file":"2019\/12\/Dr.-DellaVedova_2-e1576782988418-aspect-ratio-315x216-2.jpg","sizes":{"medium":{"file":"Dr.-DellaVedova_2-e1576782988418-aspect-ratio-315x216-2-300x206.jpg","width":300,"height":206,"mime_type":"image\/jpeg","source_url":"https:\/\/www.nosm.ca\/wp-content\/uploads\/2019\/12\/Dr.-DellaVedova_2-e1576782988418-aspect-ratio-315x216-2-300x206.jpg"},"large":{"file":"Dr.-DellaVedova_2-e1576782988418-aspect-ratio-315x216-2-1024x702.jpg","width":1024,"height":702,"mime_type":"image\/jpeg","source_url":"https:\/\/www.nosm.ca\/wp-content\/uploads\/2019\/12\/Dr.-DellaVedova_2-e1576782988418-aspect-ratio-315x216-2-1024x702.jpg"},"thumbnail":{"file":"Dr.-DellaVedova_2-e1576782988418-aspect-ratio-315x216-2-150x103.jpg","width":150,"height":103,"mime_type":"image\/jpeg","source_url":"https:\/\/www.nosm.ca\/wp-content\/uploads\/2019\/12\/Dr.-DellaVedova_2-e1576782988418-aspect-ratio-315x216-2-150x103.jpg"},"medium_large":{"file":"Dr.-DellaVedova_2-e1576782988418-aspect-ratio-315x216-2-768x526.jpg","width":768,"height":526,"mime_type":"image\/jpeg","source_url":"https:\/\/www.nosm.ca\/wp-content\/uploads\/2019\/12\/Dr.-DellaVedova_2-e1576782988418-aspect-ratio-315x216-2-768x526.jpg"},"post-thumbnail":{"file":"Dr.-DellaVedova_2-e1576782988418-aspect-ratio-315x216-2-672x372.jpg","width":672,"height":372,"mime_type":"image\/jpeg","source_url":"https:\/\/www.nosm.ca\/wp-content\/uploads\/2019\/12\/Dr.-DellaVedova_2-e1576782988418-aspect-ratio-315x216-2-672x372.jpg"},"twentyfourteen-full-width":{"file":"Dr.-DellaVedova_2-e1576782988418-aspect-ratio-315x216-2-1038x576.jpg","width":1038,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/www.nosm.ca\/wp-content\/uploads\/2019\/12\/Dr.-DellaVedova_2-e1576782988418-aspect-ratio-315x216-2-1038x576.jpg"},"full":{"file":"Dr.-DellaVedova_2-e1576782988418-aspect-ratio-315x216-2.jpg","width":1500,"height":1028,"mime_type":"image\/jpeg","source_url":"https:\/\/www.nosm.ca\/wp-content\/uploads\/2019\/12\/Dr.-DellaVedova_2-e1576782988418-aspect-ratio-315x216-2.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.nosm.ca\/wp-content\/uploads\/2019\/12\/Dr.-DellaVedova_2-e1576782988418-aspect-ratio-315x216-2.jpg","_links":{"self":[{"href":"https:\/\/www.nosm.ca\/fr\/wp-json\/wp\/v2\/media\/74938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nosm.ca\/fr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.nosm.ca\/fr\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.nosm.ca\/fr\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nosm.ca\/fr\/wp-json\/wp\/v2\/comments?post=74938"}]}}